{"id":24528,"date":"2013-05-08T12:29:20","date_gmt":"2013-05-08T12:29:20","guid":{"rendered":"https:\/\/www.senoriosderelleu.com\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/"},"modified":"2013-05-08T12:29:20","modified_gmt":"2013-05-08T12:29:20","slug":"silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013","status":"publish","type":"post","link":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/","title":{"rendered":"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013."},"content":{"rendered":"<h3 style=\"text-align: center;\">United States. In April 2013, at the second most important international competition, we were awarded a Silver Medal for the quality of our oil, a recognition that our Extra Virgin Olive Oil was one of the best in the world.<\/h3>\n<p>&nbsp;<\/p>\n<h3><strong><a href=\"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/10.2.pdf\">Download the article &#8220;Diario Informaci\u00f3n&#8221;<\/a><\/strong><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>United States. In April 2013, at the second most important international competition, we were awarded a Silver Medal for the quality of our oil, a recognition that our Extra Virgin Olive Oil was one of the best in the world. &nbsp; Download the article &#8220;Diario&#8230;<\/p>\n","protected":false},"author":1,"featured_media":24452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[880,889],"tags":[908],"class_list":["post-24528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-awards-and-prizes-de","category-news-de","tag-los-angeles-international-extra-virgin-olive-oil-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013. - Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013. - Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet\" \/>\n<meta name=\"twitter:description\" content=\"United States. In April 2013, at the second most important international competition, we were awarded a Silver Medal for the quality of our oil, a recognition that our Extra Virgin Olive Oil was one of the best in the world. &nbsp; Download the article &#8220;Diario...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/descarga-1.png\" \/>\n<meta name=\"twitter:creator\" content=\"@#\" \/>\n<meta name=\"twitter:site\" content=\"@SenoriosdRelleu\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se\u00f1or\u00edos de Relleu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/\"},\"author\":{\"name\":\"Se\u00f1or\u00edos de Relleu\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#\\\/schema\\\/person\\\/3fff15ac5394151f495a68acac6af15e\"},\"headline\":\"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013.\",\"datePublished\":\"2013-05-08T12:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/\"},\"wordCount\":60,\"publisher\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/descarga-1.png\",\"keywords\":[\"Los \u00e1ngeles International extra virgin olive oil\"],\"articleSection\":[\"Awards and Prizes\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/\",\"url\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/\",\"name\":\"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013. - Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/descarga-1.png\",\"datePublished\":\"2013-05-08T12:29:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/descarga-1.png\",\"contentUrl\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/descarga-1.png\",\"width\":224,\"height\":224,\"caption\":\"Seleccionados en 2014 por \\\"Le guide gourmands\\\". Selected in 2014 by \\\"Le guide gourmands\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#website\",\"url\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/\",\"name\":\"Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet\",\"description\":\"Mejor Aceite de Oliva Virgen Extra Gourmet Regalo Original de Alicante\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#organization\",\"name\":\"Se\u00f1orios de Relleu\",\"url\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/sr_logo_4_opciones-Paula16022012_P\u00e1gina_3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/sr_logo_4_opciones-Paula16022012_P\u00e1gina_3.jpg\",\"width\":1024,\"height\":724,\"caption\":\"Se\u00f1orios de Relleu\"},\"image\":{\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SenoriosDeRelleu\\\/\",\"https:\\\/\\\/x.com\\\/SenoriosdRelleu\",\"https:\\\/\\\/www.instagram.com\\\/senoriosdrelleu\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SenoriosdeRelleu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.senoriosderelleu.com\\\/#\\\/schema\\\/person\\\/3fff15ac5394151f495a68acac6af15e\",\"name\":\"Se\u00f1or\u00edos de Relleu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45a5e07d0fab33c1b0fc1742c483bfbe459d8e2bbfe63ba48795325c46bd0eb2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45a5e07d0fab33c1b0fc1742c483bfbe459d8e2bbfe63ba48795325c46bd0eb2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45a5e07d0fab33c1b0fc1742c483bfbe459d8e2bbfe63ba48795325c46bd0eb2?s=96&d=mm&r=g\",\"caption\":\"Se\u00f1or\u00edos de Relleu\"},\"description\":\"Se\u00f1or\u00edos de Relleu es una empresa joven con una experimentada trayectoria familiar en agronom\u00eda y olivicultura cuya actividad tiene un car\u00e1cter claramente artesanal.\",\"sameAs\":[\"https:\\\/\\\/www.senoriosderelleu.com\\\/\",\"#\",\"https:\\\/\\\/x.com\\\/#\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013. - Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/","twitter_card":"summary_large_image","twitter_title":"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013. - Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet","twitter_description":"United States. In April 2013, at the second most important international competition, we were awarded a Silver Medal for the quality of our oil, a recognition that our Extra Virgin Olive Oil was one of the best in the world. &nbsp; Download the article &#8220;Diario...","twitter_image":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/descarga-1.png","twitter_creator":"@#","twitter_site":"@SenoriosdRelleu","twitter_misc":{"Verfasst von":"Se\u00f1or\u00edos de Relleu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#article","isPartOf":{"@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/"},"author":{"name":"Se\u00f1or\u00edos de Relleu","@id":"https:\/\/www.senoriosderelleu.com\/#\/schema\/person\/3fff15ac5394151f495a68acac6af15e"},"headline":"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013.","datePublished":"2013-05-08T12:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/"},"wordCount":60,"publisher":{"@id":"https:\/\/www.senoriosderelleu.com\/#organization"},"image":{"@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/descarga-1.png","keywords":["Los \u00e1ngeles International extra virgin olive oil"],"articleSection":["Awards and Prizes","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/","url":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/","name":"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013. - Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet","isPartOf":{"@id":"https:\/\/www.senoriosderelleu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/descarga-1.png","datePublished":"2013-05-08T12:29:20+00:00","breadcrumb":{"@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#primaryimage","url":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/descarga-1.png","contentUrl":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2018\/05\/descarga-1.png","width":224,"height":224,"caption":"Seleccionados en 2014 por \"Le guide gourmands\". Selected in 2014 by \"Le guide gourmands\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.senoriosderelleu.com\/de\/silver-medal-at-the-los-angeles-international-extra-virgin-olive-oil-competition-in-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.senoriosderelleu.com\/de\/"},{"@type":"ListItem","position":2,"name":"Silver Medal at the Los Angeles International Extra Virgin Olive Oil Competition in 2013."}]},{"@type":"WebSite","@id":"https:\/\/www.senoriosderelleu.com\/#website","url":"https:\/\/www.senoriosderelleu.com\/","name":"Se\u00f1orios de Relleu | Aceite de Oliva Virgen Extra Gourmet","description":"Mejor Aceite de Oliva Virgen Extra Gourmet Regalo Original de Alicante","publisher":{"@id":"https:\/\/www.senoriosderelleu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.senoriosderelleu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.senoriosderelleu.com\/#organization","name":"Se\u00f1orios de Relleu","url":"https:\/\/www.senoriosderelleu.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.senoriosderelleu.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2015\/09\/sr_logo_4_opciones-Paula16022012_P\u00e1gina_3.jpg","contentUrl":"https:\/\/www.senoriosderelleu.com\/wp-content\/uploads\/2015\/09\/sr_logo_4_opciones-Paula16022012_P\u00e1gina_3.jpg","width":1024,"height":724,"caption":"Se\u00f1orios de Relleu"},"image":{"@id":"https:\/\/www.senoriosderelleu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenoriosDeRelleu\/","https:\/\/x.com\/SenoriosdRelleu","https:\/\/www.instagram.com\/senoriosdrelleu\/","https:\/\/www.youtube.com\/user\/SenoriosdeRelleu"]},{"@type":"Person","@id":"https:\/\/www.senoriosderelleu.com\/#\/schema\/person\/3fff15ac5394151f495a68acac6af15e","name":"Se\u00f1or\u00edos de Relleu","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/45a5e07d0fab33c1b0fc1742c483bfbe459d8e2bbfe63ba48795325c46bd0eb2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45a5e07d0fab33c1b0fc1742c483bfbe459d8e2bbfe63ba48795325c46bd0eb2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45a5e07d0fab33c1b0fc1742c483bfbe459d8e2bbfe63ba48795325c46bd0eb2?s=96&d=mm&r=g","caption":"Se\u00f1or\u00edos de Relleu"},"description":"Se\u00f1or\u00edos de Relleu es una empresa joven con una experimentada trayectoria familiar en agronom\u00eda y olivicultura cuya actividad tiene un car\u00e1cter claramente artesanal.","sameAs":["https:\/\/www.senoriosderelleu.com\/","#","https:\/\/x.com\/#"]}]}},"_links":{"self":[{"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/posts\/24528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/comments?post=24528"}],"version-history":[{"count":0,"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/posts\/24528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/media\/24452"}],"wp:attachment":[{"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/media?parent=24528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/categories?post=24528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.senoriosderelleu.com\/de\/wp-json\/wp\/v2\/tags?post=24528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}